{"id":825,"date":"2021-10-01T17:30:29","date_gmt":"2021-10-01T20:30:29","guid":{"rendered":"http:\/\/voxgroupbrasil.com\/?p=825"},"modified":"2023-09-14T14:16:26","modified_gmt":"2023-09-14T17:16:26","slug":"setembro-amarelo-acoes-em-prol-da-saude-mental-e-prevencao-contra-o-suicidio","status":"publish","type":"post","link":"https:\/\/voxgroupbrasil.com\/en\/setembro-amarelo-acoes-em-prol-da-saude-mental-e-prevencao-contra-o-suicidio\/","title":{"rendered":"SETEMBRO AMARELO: A\u00e7\u00f5es em prol da sa\u00fade mental e preven\u00e7\u00e3o ao suic\u00eddio."},"content":{"rendered":"<p style=\"text-align: center\"><span style=\"font-weight: 400\">Batizada como Setembro Amarelo, a campanha atua na manuten\u00e7\u00e3o da sa\u00fade mental e preven\u00e7\u00e3o ao suic\u00eddio em todo o Brasil.\u00a0<\/span><\/p>\n<p style=\"text-align: center\"><i><span style=\"font-weight: 400\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-827\" src=\"https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/setembro_amarelo_amafresptelepsicologia-1-750x450-1-600x360.png\" alt=\"\" width=\"600\" height=\"360\" srcset=\"https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/setembro_amarelo_amafresptelepsicologia-1-750x450-1-600x360.png 600w, https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/setembro_amarelo_amafresptelepsicologia-1-750x450-1.png 750w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/span><\/i><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><i><span style=\"font-weight: 400\">Voc\u00ea conhece a hist\u00f3ria do Setembro Amarelo?<\/span><\/i><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><span style=\"font-weight: 400\">Nos Estados Unidos, em setembro de 1994, Mike Emme, um jovem de 17 anos cometeu suic\u00eddio. O menino era muito habilidoso para trabalhos manuais e sozinho restaurou um Mustang 68, pintando-o todo de amarelo. No dia de seu vel\u00f3rio, a fam\u00edlia e colegas prestaram homenagem atrav\u00e9s de fitas e cart\u00f5es amarelos, muitos com dizeres de apoio \u00e0 quem mais estivesse passando por problemas emocionais.\u00a0<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-weight: 400\">A trag\u00e9dia foi o estopim para que se criasse um movimento de preven\u00e7\u00e3o ao suic\u00eddio, visto que cada vez mais os n\u00fameros de crian\u00e7as e adolescentes que tomavam essa atitude vinha aumentando exponencialmente.\u00a0<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-weight: 400\">Assim foi idealizado e criado o Centro de Valoriza\u00e7\u00e3o da Vida (CVV), que atua com palestras, rodas de conversas, treinamentos e principalmente atrav\u00e9s da sua hot line, gratuita e dispon\u00edvel 24h por dia, e-mail, chat online e atendimentos presenciais. Trata-se de um trabalho de acolhimento, com volunt\u00e1rios instru\u00eddos para escutarem, sem julgamentos, a pessoa necessitada do outro lado.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><i><span style=\"font-weight: 400\">Como posso participar e divulgar a campanha?\u00a0<\/span><\/i><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><span style=\"font-weight: 400\">S\u00e3o in\u00fameras as formas que voc\u00ea pode ajudar a divulgar essa campanha e criar uma rede de apoio. Compartilhar os materiais dispon\u00edveis no site do Setembro Amarelo, trazer esse debate para seu redor, seja em uma institui\u00e7\u00e3o, em casa ou na comunidade. Esperamos que nossas a\u00e7\u00f5es possam servir tamb\u00e9m de inspira\u00e7\u00e3o e apoio \u00e0 voc\u00ea.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><strong>\u00a0 1. Cartilha do Bem\u00a0<\/strong><\/p>\n<p style=\"text-align: center\"><span style=\"font-weight: 400\">Em depoimentos de pessoas que j\u00e1 realizaram uma tentativa de suicidio, muitos disseram que \u00e0s vezes, uma palavra amiga ou uma gentileza faziam com que eles mudassem de ideia no dia. Baseando-se nisso, e na cria\u00e7\u00e3o de la\u00e7os genu\u00ednos de trabalho e de amizade, para o Dia Mundial de Preven\u00e7\u00e3o ao Suic\u00eddio, 10\/09, pedimos para que cada colaborador escrevesse um depoimento sobre um colega, focando em suas qualidades e no porqu\u00ea ele \u00e9 especial.\u00a0<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-weight: 400\">\u201cO foco aqui, al\u00e9m de inform\u00e1-los em rela\u00e7\u00e3o aos sintomas, \u00e0s sa\u00eddas existentes, como procurar ajuda e sobre a exist\u00eancia do Centro de Valoriza\u00e7\u00e3o da Vida (CVV), era fazer com que eles se sentissem motivados e especiais atrav\u00e9s das palavras de seus colegas, que por conta da rotina, muitas vezes s\u00e3o elogios e depoimentos deixados de lado.\u201d disse a Assistente de Marketing, dessa forma, pudemos trazer um cart\u00e3o personalizado a cada um, unindo a informa\u00e7\u00e3o com o sentimento de pertencimento.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-828\" src=\"https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/Cartao-Vox-Setembro-Amarelo-3-300x600.png\" alt=\"\" width=\"470\" height=\"940\" srcset=\"https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/Cartao-Vox-Setembro-Amarelo-3-300x600.png 300w, https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/Cartao-Vox-Setembro-Amarelo-3-700x1400.png 700w, https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/Cartao-Vox-Setembro-Amarelo-3-768x1536.png 768w, https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/Cartao-Vox-Setembro-Amarelo-3.png 1000w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\" \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-829\" src=\"https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/WhatsApp-Image-2021-09-10-at-08.14.34-300x600.jpeg\" alt=\"\" width=\"471\" height=\"942\" srcset=\"https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/WhatsApp-Image-2021-09-10-at-08.14.34-300x600.jpeg 300w, https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/WhatsApp-Image-2021-09-10-at-08.14.34-700x1400.jpeg 700w, https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/WhatsApp-Image-2021-09-10-at-08.14.34-768x1536.jpeg 768w, https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/WhatsApp-Image-2021-09-10-at-08.14.34.jpeg 800w\" sizes=\"auto, (max-width: 471px) 100vw, 471px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><strong>2. Roda de Conversa com o Centro de Valoriza\u00e7\u00e3o da Vida (CVV)<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><span style=\"font-weight: 400\">Uma das iniciativas do CVV \u00e9 tamb\u00e9m promover esse momento de entrada em empresas, quebrando o tabu que ainda existe em conversar sobre sa\u00fade mental e suic\u00eddio. Para desmistificar o assunto, recebemos na Vox o Sr. Gilberto, volunt\u00e1rio h\u00e1 mais de 6 anos e Sr. Eliomar, volunt\u00e1rio h\u00e1 2 anos do posto do CVV de Itaja\u00ed. Nesta conversa, os dois nos apresentaram a hist\u00f3ria da institui\u00e7\u00e3o e os prop\u00f3sitos da campanha, explicando detalhadamente os pilares, valores, m\u00e9todos de preven\u00e7\u00e3o e como realizam este acolhimento que salva a vida de tantas milhares de pessoas.\u00a0<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-weight: 400\">Totalmente administrada e conduzida por volunt\u00e1rios, hoje totalizam 4 mil no Brasil todo, e enfatizam que estes n\u00fameros poderiam e deveriam ser bem maiores, visto a autoridade e hist\u00f3ria do projeto, que j\u00e1 vem marcando a vida de pessoas h\u00e1 mais de 60 anos.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-830\" src=\"https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/WhatsApp-Image-2021-09-30-at-16.20.04-600x338.jpeg\" alt=\"\" width=\"557\" height=\"314\" srcset=\"https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/WhatsApp-Image-2021-09-30-at-16.20.04-600x338.jpeg 600w, https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/WhatsApp-Image-2021-09-30-at-16.20.04-1400x788.jpeg 1400w, https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/WhatsApp-Image-2021-09-30-at-16.20.04-1536x864.jpeg 1536w, https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/WhatsApp-Image-2021-09-30-at-16.20.04.jpeg 1600w\" sizes=\"auto, (max-width: 557px) 100vw, 557px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-832\" src=\"https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/ddgdgdggd-600x316.jpeg\" alt=\"\" width=\"600\" height=\"316\" srcset=\"https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/ddgdgdggd-600x316.jpeg 600w, https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/ddgdgdggd-1400x737.jpeg 1400w, https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/ddgdgdggd-1536x809.jpeg 1536w, https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/ddgdgdggd.jpeg 1599w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><strong>3. Imers\u00e3o de Autoconhecimento.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><span style=\"font-weight: 400\">Nossa \u00faltima a\u00e7\u00e3o acerca do tema foi um Workshop pensado h\u00e1 muito tempo, que coincidiu com os temas e abordagem deste Setembro Amarelo. Nesse evento, de dura\u00e7\u00e3o de tr\u00eas horas, recebemos a Dra. Liliane Limas, psic\u00f3loga e pedagoga com \u00eanfase em psicologia cl\u00ednica e organizacional, com seu esposo, Nelson Limas, Consultor e T\u00e9cnico em Seguran\u00e7a do Trabalho, para falarmos dos 8 pilares do controle emocional e do pensamento forte.\u00a0<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-weight: 400\">Em um evento muito produtivo, tivemos a oportunidade de aprender ainda mais sobre o autoconhecimento, autoconfian\u00e7a, autoestima, autoconsci\u00eancia, autoefic\u00e1cia, autoimagem, controle emocional, pensamento positivo\u2026 em resumo, todas as coisas que agem para que tenhamos uma vida mais saud\u00e1vel, f\u00edsica, mental e emocionalmente. \u00c9 necess\u00e1rio fortalecer nosso pensamento, pois \u00e9 o grande respons\u00e1vel pela forma que passamos pela vida.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-826\" src=\"https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/imersaoo-600x429.jpeg\" alt=\"\" width=\"600\" height=\"429\" srcset=\"https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/imersaoo-600x429.jpeg 600w, https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/imersaoo-1400x1000.jpeg 1400w, https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/imersaoo.jpeg 1523w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p style=\"text-align: center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-834\" src=\"https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/WhatsApp-Image-2021-10-01-at-16.53.32-600x338.jpeg\" alt=\"\" width=\"600\" height=\"338\" srcset=\"https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/WhatsApp-Image-2021-10-01-at-16.53.32-600x338.jpeg 600w, https:\/\/voxgroupbrasil.com\/wp-content\/uploads\/WhatsApp-Image-2021-10-01-at-16.53.32.jpeg 1024w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><span style=\"font-weight: 400\">E com rela\u00e7\u00e3o \u00e0 visita dos volunt\u00e1rios do CVV, Sr. Gilberto e Sr. Eliomar, agradecemos por terem disponibilizado seu tempo e aten\u00e7\u00e3o, assim como parabenizamos pelo seu importante trabalho; em conjunto com todos os participantes desta campanha, que atuam ativamente divulgando nas redes sociais, institui\u00e7\u00f5es de trabalho e de ensino, assim como em casa e em sua comunidade.<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-weight: 400\">Que sigamos sempre cuidando de nossa sa\u00fade mental, cultivando boas rela\u00e7\u00f5es e acolhendo a quem precisa. <\/span><\/p>\n<p style=\"text-align: center\"><span style=\"font-weight: 400\">Caso voc\u00ea precise, n\u00e3o hesite em procurar ajuda!<\/span><\/p>\n<p style=\"text-align: center\"><b>CENTRO DE VALORIZA\u00c7\u00c3O DA VIDA &#8211; 188 LIGA\u00c7\u00c3O GRATUITA E 24H\u00a0<\/b><\/p>\n<p style=\"text-align: center\"><span style=\"font-weight: 400\">Para saber mais, acesse:\u00a0 <\/span><a href=\"https:\/\/www.setembroamarelo.com\/\"><span style=\"font-weight: 400\">https:\/\/www.setembroamarelo.com\/<\/span><\/a><span style=\"font-weight: 400\"> ou <\/span><a href=\"https:\/\/www.setembroamarelo.org.br\/\"><span style=\"font-weight: 400\">https:\/\/www.setembroamarelo.org.br\/<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Batizada como Setembro Amarelo, a campanha atua na manuten\u00e7\u00e3o da sa\u00fade mental e preven\u00e7\u00e3o ao suic\u00eddio em todo o Brasil.\u00a0 &nbsp; Voc\u00ea conhece a hist\u00f3ria do Setembro Amarelo? &nbsp; Nos Estados Unidos, em setembro de 1994, Mike Emme, um jovem de 17 anos cometeu suic\u00eddio. O menino era muito habilidoso para trabalhos manuais e sozinho [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,7],"tags":[13],"yst_prominent_words":[],"class_list":["post-825","post","type-post","status-publish","format-standard","hentry","category-informacoes-gerais","category-recursos-humanos","tag-saude-mental"],"_links":{"self":[{"href":"https:\/\/voxgroupbrasil.com\/en\/wp-json\/wp\/v2\/posts\/825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voxgroupbrasil.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voxgroupbrasil.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voxgroupbrasil.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/voxgroupbrasil.com\/en\/wp-json\/wp\/v2\/comments?post=825"}],"version-history":[{"count":5,"href":"https:\/\/voxgroupbrasil.com\/en\/wp-json\/wp\/v2\/posts\/825\/revisions"}],"predecessor-version":[{"id":982,"href":"https:\/\/voxgroupbrasil.com\/en\/wp-json\/wp\/v2\/posts\/825\/revisions\/982"}],"wp:attachment":[{"href":"https:\/\/voxgroupbrasil.com\/en\/wp-json\/wp\/v2\/media?parent=825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voxgroupbrasil.com\/en\/wp-json\/wp\/v2\/categories?post=825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voxgroupbrasil.com\/en\/wp-json\/wp\/v2\/tags?post=825"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/voxgroupbrasil.com\/en\/wp-json\/wp\/v2\/yst_prominent_words?post=825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}